{"id":69,"count":2,"description":"","link":"https:\/\/museedumalgretout.be\/en\/agenda\/category\/activities-and-workshops\/","name":"Activities and Workshops","slug":"activities-and-workshops","taxonomy":"tribe_events_cat","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des Activities and Workshops - Mus\u00e9e du Malgr\u00e9-Tout - Art et Arch\u00e9ologie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/museedumalgretout.be\/en\/agenda\/category\/activities-and-workshops\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Activities and Workshops - Mus\u00e9e du Malgr\u00e9-Tout - Art et Arch\u00e9ologie\" \/>\n<meta property=\"og:url\" content=\"http:\/\/museedumalgretout.be\/en\/agenda\/category\/activities-and-workshops\/\" \/>\n<meta property=\"og:site_name\" content=\"Mus\u00e9e du Malgr\u00e9-Tout - Art et Arch\u00e9ologie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\\\/\\\/museedumalgretout.be\\\/en\\\/agenda\\\/category\\\/activities-and-workshops\\\/\",\"url\":\"http:\\\/\\\/museedumalgretout.be\\\/en\\\/agenda\\\/category\\\/activities-and-workshops\\\/\",\"name\":\"Archives des Activities and Workshops - Mus\u00e9e du Malgr\u00e9-Tout - Art et Arch\u00e9ologie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/museedumalgretout.be\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/museedumalgretout.be\\\/en\\\/agenda\\\/category\\\/activities-and-workshops\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/museedumalgretout.be\\\/en\\\/agenda\\\/category\\\/activities-and-workshops\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\\\/\\\/museedumalgretout.be\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Activities and Workshops\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/museedumalgretout.be\\\/#website\",\"url\":\"https:\\\/\\\/museedumalgretout.be\\\/\",\"name\":\"Mus\u00e9e du Malgr\u00e9-Tout - Art et Arch\u00e9ologie\",\"description\":\"Arch\u00e9ologie r\u00e9gionale et plus g\u00e9n\u00e9rale de la Pr\u00e9histoire \u00e0 l&#039;Antiquit\u00e9.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/museedumalgretout.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Activities and Workshops - Mus\u00e9e du Malgr\u00e9-Tout - Art et Arch\u00e9ologie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/museedumalgretout.be\/en\/agenda\/category\/activities-and-workshops\/","og_locale":"en_US","og_type":"article","og_title":"Archives des Activities and Workshops - Mus\u00e9e du Malgr\u00e9-Tout - Art et Arch\u00e9ologie","og_url":"http:\/\/museedumalgretout.be\/en\/agenda\/category\/activities-and-workshops\/","og_site_name":"Mus\u00e9e du Malgr\u00e9-Tout - Art et Arch\u00e9ologie","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/museedumalgretout.be\/en\/agenda\/category\/activities-and-workshops\/","url":"http:\/\/museedumalgretout.be\/en\/agenda\/category\/activities-and-workshops\/","name":"Archives des Activities and Workshops - Mus\u00e9e du Malgr\u00e9-Tout - Art et Arch\u00e9ologie","isPartOf":{"@id":"https:\/\/museedumalgretout.be\/#website"},"breadcrumb":{"@id":"http:\/\/museedumalgretout.be\/en\/agenda\/category\/activities-and-workshops\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"http:\/\/museedumalgretout.be\/en\/agenda\/category\/activities-and-workshops\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/museedumalgretout.be\/en\/"},{"@type":"ListItem","position":2,"name":"Activities and Workshops"}]},{"@type":"WebSite","@id":"https:\/\/museedumalgretout.be\/#website","url":"https:\/\/museedumalgretout.be\/","name":"Mus\u00e9e du Malgr\u00e9-Tout - Art et Arch\u00e9ologie","description":"Arch\u00e9ologie r\u00e9gionale et plus g\u00e9n\u00e9rale de la Pr\u00e9histoire \u00e0 l&#039;Antiquit\u00e9.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/museedumalgretout.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/museedumalgretout.be\/en\/wp-json\/wp\/v2\/tribe_events_cat\/69","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/museedumalgretout.be\/en\/wp-json\/wp\/v2\/tribe_events_cat"}],"about":[{"href":"https:\/\/museedumalgretout.be\/en\/wp-json\/wp\/v2\/taxonomies\/tribe_events_cat"}],"wp:post_type":[{"href":"https:\/\/museedumalgretout.be\/en\/wp-json\/wp\/v2\/tribe_events?tribe_events_cat=69"},{"href":"https:\/\/museedumalgretout.be\/en\/wp-json\/wp\/v2\/tec_calendar_embed?tribe_events_cat=69"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}