{"id":1549,"date":"2024-11-06T11:01:07","date_gmt":"2024-11-06T10:01:07","guid":{"rendered":"https:\/\/museedumalgretout.be\/cedarc-editions\/"},"modified":"2025-02-26T11:18:26","modified_gmt":"2025-02-26T10:18:26","slug":"cedarc-editions","status":"publish","type":"page","link":"https:\/\/museedumalgretout.be\/en\/cedarc-editions\/","title":{"rendered":"Cedarc Editions"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;http:\/\/museedumalgretout.be\/wp-content\/uploads\/2024\/10\/Musee-sortie-scolaire.png&#8221; custom_padding=&#8221;30px||30px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row make_equal=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;80%&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; global_colors_info=&#8221;{}&#8221; width_last_edited=&#8221;on|phone&#8221; width_phone=&#8221;90%&#8221; max_width_last_edited=&#8221;on|phone&#8221; max_width_phone=&#8221;90%&#8221; max_width_tablet=&#8221;80%&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; custom_padding=&#8221;50px|50px|50px|50px|true|true&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; custom_padding_phone=&#8221;30px|5px|30px|5px|true|true&#8221; sticky_enabled=&#8221;0&#8243; custom_padding_tablet=&#8221;50px|50px|50px|50px|true|true&#8221;][et_pb_text _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#252930&#8243; header_font=&#8221;|800|||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;40px&#8221; header_line_height=&#8221;1.1em&#8221; custom_margin=&#8221;||20px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1 style=\"text-align: center;\">Cedarc Editions<\/h1>\n<p>[\/et_pb_text][et_pb_divider color=&#8221;#BA2320&#8243; divider_weight=&#8221;6px&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;35%&#8221; module_alignment=&#8221;center&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; width_last_edited=&#8221;on|phone&#8221; width_phone=&#8221;86%&#8221; sticky_enabled=&#8221;0&#8243; width_tablet=&#8221;35%&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#252930&#8243; custom_padding=&#8221;10px||10px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;90%&#8221; custom_padding=&#8221;5px||5px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][dsm_breadcrumbs home_text=&#8221;Scientific division&#8221; use_custom_home_url_link=&#8221;on&#8221; home_url_link=&#8221;#&#8221; show_home_icon=&#8221;off&#8221; separator_icon=&#8221;&#xf0da;||fa||900&#8243; items_bg_color=&#8221;RGBA(255,255,255,0)&#8221; current_bg_color=&#8221;RGBA(255,255,255,0)&#8221; items_padding=&#8221;0px|20px|0px|0px|false|false&#8221; current_padding=&#8221;0px|0px|0px|20px|false|false&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; items_font=&#8221;|||on|||||&#8221; items_text_color=&#8221;#FFFFFF&#8221; items_font_size=&#8221;18px&#8221; separators_text_color=&#8221;#BA2320&#8243; separators_font_size=&#8221;30px&#8221; current_font=&#8221;|||on|||||&#8221; current_text_color=&#8221;#FFFFFF&#8221; current_font_size=&#8221;18px&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; items_padding_last_edited=&#8221;on|phone&#8221; items_padding_phone=&#8221;|10px|||false|false&#8221; items_font_size_last_edited=&#8221;on|phone&#8221; items_font_size_phone=&#8221;16px&#8221; current_padding_last_edited=&#8221;on|phone&#8221; current_padding_phone=&#8221;0px|0px|0px|10px|false|false&#8221; current_font_size_last_edited=&#8221;on|phone&#8221; current_font_size_phone=&#8221;16px&#8221; sticky_enabled=&#8221;0&#8243; items_padding_tablet=&#8221;0px|20px|0px|0px|false|false&#8221; items_font_size_tablet=&#8221;18px&#8221; current_padding_tablet=&#8221;0px|0px|0px|20px|false|false&#8221; current_font_size_tablet=&#8221;18px&#8221;][\/dsm_breadcrumbs][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;50px||10px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_4,3_4&#8243; use_custom_gutter=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;60%&#8221; max_width=&#8221;60%&#8221; hover_enabled=&#8221;0&#8243; custom_css_main_element=&#8221;display:flex;||align-items:center;&#8221; global_colors_info=&#8221;{}&#8221; width_last_edited=&#8221;on|phone&#8221; width_phone=&#8221;80%&#8221; max_width_last_edited=&#8221;on|phone&#8221; max_width_phone=&#8221;80%&#8221; custom_css_main_element_last_edited=&#8221;on|phone&#8221; sticky_enabled=&#8221;0&#8243; custom_css_main_element_phone=&#8221;display:inline;||align-items:center;&#8221; width_tablet=&#8221;60%&#8221; max_width_tablet=&#8221;60%&#8221; custom_css_main_element_tablet=&#8221;display:flex;||align-items:center;&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; custom_padding_phone=&#8221;|30px||30px|false|true&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_image src=&#8221;http:\/\/museedumalgretout.be\/wp-content\/uploads\/2024\/11\/Favicon-rouge-musee.png&#8221; title_text=&#8221;Favicon red museum&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; animation_style=&#8221;fade&#8221; animation_duration=&#8221;1500ms&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; width_last_edited=&#8221;on|phone&#8221; width_phone=&#8221;40%&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; custom_padding_phone=&#8221;|30px||30px|false|true&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_text _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|800|||||||&#8221; header_2_font_size=&#8221;32px&#8221; header_2_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||15px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 style=\"text-align: left;\"><span>Dissemination tools: Sharing archaeology for all<\/span><\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Disseminating information is a fundamental mission of an archaeological museum and research center. That&#8217;s why, since 1985, Cedarc \/ Mus\u00e9e du Malgr\u00e9-Tout has created several tools. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;40px||80px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; use_custom_gutter=&#8221;on&#8221; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;90%&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; width_last_edited=&#8221;on|phone&#8221; width_phone=&#8221;85%&#8221; max_width_last_edited=&#8221;on|phone&#8221; max_width_phone=&#8221;85%&#8221; sticky_enabled=&#8221;0&#8243; width_tablet=&#8221;90%&#8221; max_width_tablet=&#8221;90%&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][dsm_image_reveal reveal_text=&#8221;Exhibition catalogs&#8221; src=&#8221;http:\/\/museedumalgretout.be\/wp-content\/uploads\/2025\/02\/Catalogues-dexpositions.jpg&#8221; title_text=&#8221;Exhibition catalogs&#8221; reveal_overlay_color=&#8221;#BA2320&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; reveal_text_text_color=&#8221;#FFFFFF&#8221; reveal_text_font_size=&#8221;24px&#8221; reveal_text_line_height=&#8221;1.2em&#8221; global_colors_info=&#8221;{}&#8221;][\/dsm_image_reveal][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: left;\"><span>The Mus\u00e9e du Malgr\u00e9-Tout exhibition catalogs are Cedarc&#8217;s exhibition catalogs, aimed at a wide audience.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][dsm_image_reveal reveal_text=&#8221;The Archaeo-Situla&#8221; src=&#8221;http:\/\/museedumalgretout.be\/wp-content\/uploads\/2025\/02\/archeo-situla.jpg&#8221; title_text=&#8221;archeo-situla&#8221; reveal_overlay_color=&#8221;#BA2320&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; reveal_text_text_color=&#8221;#FFFFFF&#8221; reveal_text_font_size=&#8221;24px&#8221; reveal_text_line_height=&#8221;1.2em&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_margin_phone=&#8221;50px||||false|false&#8221; sticky_enabled=&#8221;0&#8243;][\/dsm_image_reveal][et_pb_text _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: left;\"><span>Arch\u00e9o-Situla, which since 1989 has been publishing research, <\/span>excavations<span>  and local archaeological discoveries, as well as a number of more general studies. The magazine has merged with Situla Arduennae, published by the Centre de Recherches Arch\u00e9ologiques en Ardenne (CRAA). <\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][dsm_image_reveal reveal_text=&#8221;Artifacts&#8221; src=&#8221;http:\/\/museedumalgretout.be\/wp-content\/uploads\/2025\/02\/artefacts.jpg&#8221; title_text=&#8221;artifacts&#8221; reveal_overlay_color=&#8221;#BA2320&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; reveal_text_text_color=&#8221;#FFFFFF&#8221; reveal_text_font_size=&#8221;24px&#8221; reveal_text_line_height=&#8221;1.2em&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_margin_phone=&#8221;50px||||false|false&#8221; sticky_enabled=&#8221;0&#8243;][\/dsm_image_reveal][et_pb_text _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>Artifacts, scientific monographs distributed worldwide<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][dsm_image_reveal reveal_text=&#8221;Educational documents&#8221; src=&#8221;http:\/\/museedumalgretout.be\/wp-content\/uploads\/2025\/02\/document-pedagogique.jpg&#8221; title_text=&#8221;educational-document&#8221; reveal_overlay_color=&#8221;#BA2320&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; reveal_text_text_color=&#8221;#FFFFFF&#8221; reveal_text_font_size=&#8221;24px&#8221; reveal_text_line_height=&#8221;1.2em&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_margin_phone=&#8221;50px||||false|false&#8221; sticky_enabled=&#8221;0&#8243;][\/dsm_image_reveal][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>Educational material for young people and teachers, introducing them to various areas of archaeology through comic strips.  <\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;http:\/\/museedumalgretout.be\/wp-content\/uploads\/2025\/02\/DSC_1693-scaled.jpg&#8221; parallax=&#8221;on&#8221; custom_padding=&#8221;120px||120px||true|false&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; custom_padding_phone=&#8221;90px||90px||true|false&#8221; sticky_enabled=&#8221;0&#8243; custom_padding_tablet=&#8221;120px||120px||true|false&#8221;][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;rgba(235,236,240,0.8)&#8221; custom_padding=&#8221;40px|60px|40px|60px|false|true&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; custom_padding_phone=&#8221;40px|30px|40px|30px|false|true&#8221; sticky_enabled=&#8221;0&#8243; custom_padding_tablet=&#8221;40px|60px|40px|60px|false|true&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|800|||||||&#8221; header_2_font_size=&#8221;32px&#8221; header_2_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||15px||false|false&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_2_font_size_phone=&#8221;29px&#8221; sticky_enabled=&#8221;0&#8243; header_2_font_size_tablet=&#8221;32px&#8221;]<\/p>\n<h2 style=\"text-align: center;\">Cedarc editions on our online store<\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||35px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\">All our publications are available in our online store. Find them today! <\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/www.museedumalgretout.be\/shop\/fr\/2-produits&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;To the store&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;16px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#BA2320&#8243; button_border_width=&#8221;2px&#8221; button_border_color=&#8221;#BA2320&#8243; button_border_radius=&#8221;0px&#8221; button_font=&#8221;|||on|||||&#8221; button_use_icon=&#8221;off&#8221; custom_padding=&#8221;|30px||30px|false|true&#8221; global_colors_info=&#8221;{}&#8221; button_border_width__hover_enabled=&#8221;on|hover&#8221; button_border_width__hover=&#8221;2px&#8221; button_text_color__hover_enabled=&#8221;on|hover&#8221; button_text_color__hover=&#8221;#BA2320&#8243; button_bg_color__hover_enabled=&#8221;on|hover&#8221; button_bg_color__hover=&#8221;#FFFFFF&#8221; button_bg_enable_color__hover=&#8221;on&#8221; button_border_color__hover_enabled=&#8221;on|hover&#8221; button_border_color__hover=&#8221;#BA2320&#8243; button_text_size__hover_enabled=&#8221;on|hover&#8221; button_text_size__hover=&#8221;16px&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cedarc Editions<div class=\"et_pb_module dsm_breadcrumbs dsm_breadcrumbs_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<nav class=\"dsm_breadcrumbs_wrap\">\n\t\t\t\t<ul class=\"dsm_breadcrumbs\" itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\">\t\t\t<li class=\"dsm_breadcrumbs_item dsm_home_item dsm_home_item_custom\" itemprop=\"itemListElement\" itemscope\n\t\t\titemtype=\"https:\/\/schema.org\/ListItem\">\n\t\t\t\t<a href=\"#\" itemprop=\"item\" target=\"\">\n\t\t\t\t\t<span class='dsm_home_text_wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"dsm_home_text\" itemprop=\"name\">\n\t\t\t\t\t\t\t\tScientific division\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t<meta itemprop=\"position\" content=\"1\" \/>\n\t\t\t<\/li>\n\n\t\t<li class=\"dsm_breadcrumbs_separator\"> <span class=\"et-pb-icon dsm_separator_icon\">&#xf0da;<\/span><\/li><\/ul>\n\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t<\/div>Dissemination tools: Sharing archaeology for allDisseminating information is a fundamental mission of an archaeological museum and research center. That&#8217;s why, since 1985, Cedarc \/ Mus\u00e9e du Malgr\u00e9-Tout has created several tools. <div class=\"et_pb_module dsm_image_reveal dsm_image_reveal_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dsm-image-reveal et_pb_bg_layout_dark et_always_center_on_mobile\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"dsm-image-wrapper\"><span class=\"et_pb_image_wrap\"><div class=\"dsm-image-reveal-overlay\"><\/div><img decoding=\"async\" src=\"http:\/\/museedumalgretout.be\/wp-content\/uploads\/2025\/02\/Catalogues-dexpositions.jpg\" alt=\"\" title=\"Exhibition catalogs\" \/><div class=\"dsm-image-reveal-text-wrapper\"><h3 class=\"dsm-image-reveal-text et_pb_module_header et_pb_text_align_center\" data-splitting>Exhibition catalogs<\/h3><\/div><\/span><\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>The Mus\u00e9e du Malgr\u00e9-Tout exhibition catalogs are Cedarc&#8217;s exhibition catalogs, aimed at a wide audience.<div class=\"et_pb_module dsm_image_reveal dsm_image_reveal_1\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dsm-image-reveal et_pb_bg_layout_dark et_always_center_on_mobile\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"dsm-image-wrapper\"><span class=\"et_pb_image_wrap\"><div class=\"dsm-image-reveal-overlay\"><\/div><img decoding=\"async\" src=\"http:\/\/museedumalgretout.be\/wp-content\/uploads\/2025\/02\/archeo-situla.jpg\" alt=\"\" title=\"archeo-situla\" \/><div class=\"dsm-image-reveal-text-wrapper\"><h3 class=\"dsm-image-reveal-text et_pb_module_header et_pb_text_align_center\" data-splitting>The Archaeo-Situla<\/h3><\/div><\/span><\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>Arch\u00e9o-Situla, which since 1989 has been publishing research, excavations and local archaeological discoveries, as well as a number of more general studies. The magazine has merged with Situla Arduennae, published by the Centre de Recherches Arch\u00e9ologiques en Ardenne (CRAA). <div class=\"et_pb_module dsm_image_reveal dsm_image_reveal_2\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dsm-image-reveal et_pb_bg_layout_dark et_always_center_on_mobile\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"dsm-image-wrapper\"><span class=\"et_pb_image_wrap\"><div class=\"dsm-image-reveal-overlay\"><\/div><img decoding=\"async\" src=\"http:\/\/museedumalgretout.be\/wp-content\/uploads\/2025\/02\/artefacts.jpg\" alt=\"\" title=\"artifacts\" \/><div class=\"dsm-image-reveal-text-wrapper\"><h3 class=\"dsm-image-reveal-text et_pb_module_header et_pb_text_align_center\" data-splitting>Artifacts<\/h3><\/div><\/span><\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>Artifacts, scientific monographs distributed worldwide<div class=\"et_pb_module dsm_image_reveal dsm_image_reveal_3\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<div class=\"dsm-image-reveal et_pb_bg_layout_dark et_always_center_on_mobile\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"dsm-image-wrapper\"><span class=\"et_pb_image_wrap\"><div class=\"dsm-image-reveal-overlay\"><\/div><img decoding=\"async\" src=\"http:\/\/museedumalgretout.be\/wp-content\/uploads\/2025\/02\/document-pedagogique.jpg\" alt=\"\" title=\"educational-document\" \/><div class=\"dsm-image-reveal-text-wrapper\"><h3 class=\"dsm-image-reveal-text et_pb_module_header et_pb_text_align_center\" data-splitting>Educational documents<\/h3><\/div><\/span><\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>Educational material for young people and teachers, introducing them to various areas of archaeology through comic strips. Cedarc editions on [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-1549","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cedarc Editions - Mus\u00e9e du Malgr\u00e9-Tout - Art et Arch\u00e9ologie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/museedumalgretout.be\/en\/cedarc-editions\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cedarc Editions - Mus\u00e9e du Malgr\u00e9-Tout - Art et Arch\u00e9ologie\" \/>\n<meta property=\"og:description\" content=\"Cedarc EditionsDissemination tools: Sharing archaeology for allDisseminating information is a fundamental mission of an archaeological museum and research center. That&#039;s why, since 1985, Cedarc \/ Mus\u00e9e du Malgr\u00e9-Tout has created several tools. The Mus\u00e9e du Malgr\u00e9-Tout exhibition catalogs are Cedarc&#039;s exhibition catalogs, aimed at a wide audience.Arch\u00e9o-Situla, which since 1989 has been publishing research, excavations and local archaeological discoveries, as well as a number of more general studies. The magazine has merged with Situla Arduennae, published by the Centre de Recherches Arch\u00e9ologiques en Ardenne (CRAA). Artifacts, scientific monographs distributed worldwideEducational material for young people and teachers, introducing them to various areas of archaeology through comic strips. Cedarc editions on [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/museedumalgretout.be\/en\/cedarc-editions\/\" \/>\n<meta property=\"og:site_name\" content=\"Mus\u00e9e du Malgr\u00e9-Tout - Art et Arch\u00e9ologie\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-26T10:18:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/museedumalgretout.be\\\/en\\\/cedarc-editions\\\/\",\"url\":\"http:\\\/\\\/museedumalgretout.be\\\/en\\\/cedarc-editions\\\/\",\"name\":\"Cedarc Editions - Mus\u00e9e du Malgr\u00e9-Tout - Art et Arch\u00e9ologie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/museedumalgretout.be\\\/#website\"},\"datePublished\":\"2024-11-06T10:01:07+00:00\",\"dateModified\":\"2025-02-26T10:18:26+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/museedumalgretout.be\\\/en\\\/cedarc-editions\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/museedumalgretout.be\\\/en\\\/cedarc-editions\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/museedumalgretout.be\\\/en\\\/cedarc-editions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\\\/\\\/museedumalgretout.be\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cedarc Editions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/museedumalgretout.be\\\/#website\",\"url\":\"https:\\\/\\\/museedumalgretout.be\\\/\",\"name\":\"Mus\u00e9e du Malgr\u00e9-Tout - Art et Arch\u00e9ologie\",\"description\":\"Arch\u00e9ologie r\u00e9gionale et plus g\u00e9n\u00e9rale de la Pr\u00e9histoire \u00e0 l&#039;Antiquit\u00e9.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/museedumalgretout.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cedarc Editions - Mus\u00e9e du Malgr\u00e9-Tout - Art et Arch\u00e9ologie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/museedumalgretout.be\/en\/cedarc-editions\/","og_locale":"en_US","og_type":"article","og_title":"Cedarc Editions - Mus\u00e9e du Malgr\u00e9-Tout - Art et Arch\u00e9ologie","og_description":"Cedarc EditionsDissemination tools: Sharing archaeology for allDisseminating information is a fundamental mission of an archaeological museum and research center. That's why, since 1985, Cedarc \/ Mus\u00e9e du Malgr\u00e9-Tout has created several tools. The Mus\u00e9e du Malgr\u00e9-Tout exhibition catalogs are Cedarc's exhibition catalogs, aimed at a wide audience.Arch\u00e9o-Situla, which since 1989 has been publishing research, excavations and local archaeological discoveries, as well as a number of more general studies. The magazine has merged with Situla Arduennae, published by the Centre de Recherches Arch\u00e9ologiques en Ardenne (CRAA). Artifacts, scientific monographs distributed worldwideEducational material for young people and teachers, introducing them to various areas of archaeology through comic strips. Cedarc editions on [&hellip;]","og_url":"http:\/\/museedumalgretout.be\/en\/cedarc-editions\/","og_site_name":"Mus\u00e9e du Malgr\u00e9-Tout - Art et Arch\u00e9ologie","article_modified_time":"2025-02-26T10:18:26+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/museedumalgretout.be\/en\/cedarc-editions\/","url":"http:\/\/museedumalgretout.be\/en\/cedarc-editions\/","name":"Cedarc Editions - Mus\u00e9e du Malgr\u00e9-Tout - Art et Arch\u00e9ologie","isPartOf":{"@id":"https:\/\/museedumalgretout.be\/#website"},"datePublished":"2024-11-06T10:01:07+00:00","dateModified":"2025-02-26T10:18:26+00:00","breadcrumb":{"@id":"http:\/\/museedumalgretout.be\/en\/cedarc-editions\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/museedumalgretout.be\/en\/cedarc-editions\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/museedumalgretout.be\/en\/cedarc-editions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/museedumalgretout.be\/en\/"},{"@type":"ListItem","position":2,"name":"Cedarc Editions"}]},{"@type":"WebSite","@id":"https:\/\/museedumalgretout.be\/#website","url":"https:\/\/museedumalgretout.be\/","name":"Mus\u00e9e du Malgr\u00e9-Tout - Art et Arch\u00e9ologie","description":"Arch\u00e9ologie r\u00e9gionale et plus g\u00e9n\u00e9rale de la Pr\u00e9histoire \u00e0 l&#039;Antiquit\u00e9.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/museedumalgretout.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/museedumalgretout.be\/en\/wp-json\/wp\/v2\/pages\/1549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/museedumalgretout.be\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/museedumalgretout.be\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/museedumalgretout.be\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/museedumalgretout.be\/en\/wp-json\/wp\/v2\/comments?post=1549"}],"version-history":[{"count":3,"href":"https:\/\/museedumalgretout.be\/en\/wp-json\/wp\/v2\/pages\/1549\/revisions"}],"predecessor-version":[{"id":2129,"href":"https:\/\/museedumalgretout.be\/en\/wp-json\/wp\/v2\/pages\/1549\/revisions\/2129"}],"wp:attachment":[{"href":"https:\/\/museedumalgretout.be\/en\/wp-json\/wp\/v2\/media?parent=1549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}